{"id":8180,"date":"2020-02-13T13:18:34","date_gmt":"2020-02-13T12:18:34","guid":{"rendered":"http:\/\/corsi.fotografareindigitale.com\/corsi\/?post_type=course&#038;p=8180"},"modified":"2020-11-26T16:58:01","modified_gmt":"2020-11-26T15:58:01","slug":"i-veloci-la-stabilizzazione","status":"publish","type":"course","link":"https:\/\/corsi.fotografareindigitale.com\/corsi\/course\/i-veloci-la-stabilizzazione\/","title":{"rendered":"I Veloci &#8211; La Stabilizzazione"},"content":{"rendered":"<p>La stabilizzazione delle immagini \u00e8 disponibile in una variet\u00e0 di nomi e tipi diversi. Che si chiami O.I.S. (Optical Image Stabilization), VC (Vibration Compensation), VR (Vibration Reduction), IBIS (In-Body Image Stabilization) o semplicemente IS (Image Stabilization), tutto ci\u00f2 fa fondamentalmente la stessa cosa &#8211; controlla gli effetti delle vibrazioni della fotocamera per produrre immagini pi\u00f9 nitide. Con gli ultimi anni, la stabilizzazione dell&#8217;immagine del corpo \u00e8 stata creata, e la maggior parte delle ultime versioni di obiettivi Canon e Nikon sono dotate di una certa iterazione di stabilizzazione dell&#8217;immagine. Ma cosa significa tutto questo e come funziona fondamentalmente la stabilizzazione dell&#8217;immagine?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La stabilizzazione delle immagini \u00e8 disponibile in una variet\u00e0 di nomi e tipi diversi. Che si chiami O.I.S. (Optical Image &hellip;<\/p>\n","protected":false},"author":8,"featured_media":10982,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"pmpro_default_level":"","_vibebp_attr":"","_vibebp_dimensions":"","_vibebp_responsive_height":"","_vibebp_accordion_ie_support":"","footnotes":""},"course-cat":[179,176],"coauthors":[182],"class_list":["post-8180","course","type-course","status-publish","has-post-thumbnail","hentry","course-cat-fotografia","course-cat-i-veloci","pmpro-has-access","user-has-not-earned"],"_links":{"self":[{"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/course\/8180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/types\/course"}],"author":[{"embeddable":true,"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/comments?post=8180"}],"version-history":[{"count":3,"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/course\/8180\/revisions"}],"predecessor-version":[{"id":8209,"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/course\/8180\/revisions\/8209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/media\/10982"}],"wp:attachment":[{"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/media?parent=8180"}],"wp:term":[{"taxonomy":"course-cat","embeddable":true,"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/course-cat?post=8180"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/corsi.fotografareindigitale.com\/corsi\/wp-json\/wp\/v2\/coauthors?post=8180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}